{"id":46,"date":"2003-03-12T21:38:40","date_gmt":"2003-03-12T20:38:40","guid":{"rendered":"http:\/\/www.alpavista.ch\/Alp11\/?p=46"},"modified":"2016-09-24T18:37:55","modified_gmt":"2016-09-24T17:37:55","slug":"2003-un-hiver-a-vous-faire-aimer-lhiver","status":"publish","type":"post","link":"https:\/\/alpavista.ch\/Alp11\/2003\/03\/12\/2003-un-hiver-a-vous-faire-aimer-lhiver\/","title":{"rendered":"2003 \u2013 Un hiver \u00e0 vous faire aimer l\u2019hiver"},"content":{"rendered":"<p>Ponctuel, g\u00e9n\u00e9reux en neige, froid et malgr\u00e9 tout ensoleill\u00e9, que demander de plus \u00e0 une saison qui avait pris la mauvaise habitude de se faire de plus en plus capricieuse sous nos latitudes. Finalement, c\u2019est beau un hiver\u2026 en hiver.<br \/>\nCelui qui est sur le point de s\u2019achever va brillamment se r\u00e9concilier avec ses adeptes les plus exigeants et peut-\u00eatre \u00e9galement, qui sait, avec ses d\u00e9tracteurs les plus inflexibles.<\/p>\n<p><!--more--><br \/>\nDurant les 2 derni\u00e8res d\u00e9cennies, l\u2019hiver n\u2019a que trop souvent \u00e9t\u00e9 fait de promesses non tenues, de radoucissements assassins, d\u2019humidit\u00e9 tenace ou de froideurs interminables et d\u00e9sesp\u00e9r\u00e9ment s\u00e8ches pour ne pas se r\u00e9jouir du mill\u00e9sime 2003, de son \u00e9panouissement et de sa pl\u00e9nitude.<\/p>\n<p>L\u2019ivresse d\u2019une s\u00e9ance de glisse, le plaisir d\u2019une rando calme et feutr\u00e9e, le bonheur d\u2019une empreinte laiss\u00e9e sur un espace immacul\u00e9 et inlassablement ravaud\u00e9, la po\u00e9sie d\u2019une joyeuse farandole de flocons virevoltants, la violence d\u2019un ciel sombre et  mena\u00e7ant ou la s\u00e9r\u00e9nit\u00e9 d\u2019une nature endormie sous sa cape enneig\u00e9e, les raisons de se r\u00e9jouir de la bonne tenue de celle que l\u2019on nomme injustement la mauvaise saison sont multiples et tr\u00e8s diverses.<\/p>\n<p>A la veille de sa belle mort, je trouve qu\u2019il est temps de rendre hommage \u00e0 ce splendide hiver que nous venons de vivre par une s\u00e9rie de photos hivernales prises \u00e0 travers les Alpes durant les mois \u00e9coul\u00e9s. Du Vercors au Valais, en passant par la Chartreuse, l\u2019Oisans, Belledone, la Haute-Savoie et le Val d\u2019Aosta,<\/p>\n<p>PS1. Un merci tout particulier \u00e0 mon ami <a href=\"http:\/\/www.lermite.net\/\" target=\"_blank\"><strong> l\u2019Ermite<\/strong><\/a> pour m\u2019avoir autoris\u00e9 \u00e0 disposer de ses plus beaux clich\u00e9s hivernaux et pour avoir pris le temps de m\u2019\u00e9clairer sur leur emplacement g\u00e9ographique pr\u00e9cis.<\/p>\n<p>PS2. Cette galerie d\u2019images n\u2019est ni d\u00e9finitive, ni ferm\u00e9e. Si vous avez vous aussi des t\u00e9moignages photographiques qui rendent gr\u00e2ce \u00e0 la saison hivernale, ne vous privez pas pour compl\u00e9ter ce petit hommage illustr\u00e9.<\/p>\n<input class=\"fooboxshare_post_id\" type=\"hidden\" value=\"46\"\/>","protected":false},"excerpt":{"rendered":"<p>Ponctuel, g\u00e9n\u00e9reux en neige, froid et malgr\u00e9 tout ensoleill\u00e9, que demander de plus \u00e0 une saison qui avait pris la mauvaise habitude de se faire de plus en plus capricieuse sous nos latitudes. Finalement, c\u2019est beau un hiver\u2026 en hiver. <br \/>\n Celui qui est sur le point de s\u2019achever va brillamment se r\u00e9concilier avec ses adeptes les plus exigeants et peut-\u00eatre \u00e9galement, qui sait, avec ses d\u00e9tracteurs les plus inflexibles. <\/p>\n","protected":false},"author":2,"featured_media":8629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,356],"tags":[399,398,400],"class_list":["post-46","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-chroniques","category-en-haut-chroniques","tag-climat","tag-hiver","tag-meteo"],"_links":{"self":[{"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/posts\/46","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/comments?post=46"}],"version-history":[{"count":0,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/posts\/46\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/media\/8629"}],"wp:attachment":[{"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/media?parent=46"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/categories?post=46"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/tags?post=46"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}