{"id":5848,"date":"2015-06-20T19:48:50","date_gmt":"2015-06-20T18:48:50","guid":{"rendered":"http:\/\/www.alpavista.ch\/Alp11\/?p=5848"},"modified":"2022-12-09T17:41:04","modified_gmt":"2022-12-09T16:41:04","slug":"barasson","status":"publish","type":"post","link":"https:\/\/alpavista.ch\/Alp11\/2015\/06\/20\/barasson\/","title":{"rendered":"Barasson"},"content":{"rendered":"<p>Partir reconna\u00eetre un nouveau parcours VTT est souvent hasardeux, tant il est difficile de pr\u00e9dire ce que les traits till\u00e9s de la carte r\u00e9v\u00e8leront sur le terrain. C\u2019est un principe de base, et en \u00ab principe \u00bb on le sait. Oui, mais il y a des reconnaissances plus \u00ab gal\u00e8res \u00bb que d\u2019autres. Comme par exemple celle qui consistait \u00e0 aller reconna\u00eetre le chemin transfrontalier passant par le(s) col(s) de Barasson, Est et Ouest, en juin, \u00e0 plus de 2&rsquo;600 m\u00e8tres d\u2019altitude, bien trop t\u00f4t pour esp\u00e9rer \u00e9viter les derniers n\u00e9v\u00e9s et avec une m\u00e9t\u00e9o dont \u00ab fra\u00eeche \u00bb n\u2019aura finalement \u00e9t\u00e9 que le pr\u00e9nom.<br \/>\n<!--more--><\/p>\n<p>Barasson, une id\u00e9e \u00e0 la con !<\/p>\n<style type=\"text\/css\">\n#foogallery-gallery-36795 .fg-image { width: 101px; }\n#foogallery-gallery-36795 { --fg-gutter: 1px; }<\/style>\n\t\t\t<div class=\"foogallery foogallery-container foogallery-default foogallery-lightbox-none fg-left fg-default fg-ready fg-light fg-loading-default fg-loaded-fade-in fg-preset fg-selena fg-preset-small fg-preset fg-selena fg-preset-small\" id=\"foogallery-gallery-36795\" data-foogallery=\"{&quot;item&quot;:{&quot;showCaptionTitle&quot;:false,&quot;showCaptionDescription&quot;:true},&quot;lazy&quot;:true,&quot;state&quot;:{&quot;enabled&quot;:true,&quot;mask&quot;:&quot;foogallery-{id}&quot;}}\" style=\"--fg-title-line-clamp: 0; --fg-description-line-clamp: 0;\" >\n\t<div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_001.jpg\" data-caption-title=\"Le b\u00e9b\u00e9 se pr\u00e9sentait pourtant bien, surtout apr\u00e8s avoir exp\u00e9di\u00e9s les quelques kilom\u00e8tres de bitume puants et p\u00e9taradants qui m\u00e8nent au col du Grand St-Bernard.\" data-caption-desc=\"Le b\u00e9b\u00e9 se pr\u00e9sentait pourtant bien, surtout apr\u00e8s avoir exp\u00e9di\u00e9s les quelques kilom\u00e8tres de bitume puants et p\u00e9taradants qui m\u00e8nent au col du Grand St-Bernard.\" data-attachment-id=\"36806\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_001\" title=\"Le b\u00e9b\u00e9 se pr\u00e9sentait pourtant bien, surtout apr\u00e8s avoir exp\u00e9di\u00e9s les quelques kilom\u00e8tres de bitume puants et p\u00e9taradants qui m\u00e8nent au col du Grand St-Bernard.\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_001\/711872129.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Le b\u00e9b\u00e9 se pr\u00e9sentait pourtant bien, surtout apr\u00e8s avoir exp\u00e9di\u00e9s les quelques kilom\u00e8tres de bitume puants et p\u00e9taradants qui m\u00e8nent au col du Grand St-Bernard.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_002.jpg\" data-caption-title=\"Notre itin\u00e9raire h\u00e9sitait certes entre son envie de devenir un cours d&#039;eau et sa vocation originale de chemin...\" data-caption-desc=\"Notre itin\u00e9raire h\u00e9sitait certes entre son envie de devenir un cours d&#039;eau et sa vocation originale de chemin...\" data-attachment-id=\"36805\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_002\" title=\"Notre itin\u00e9raire h\u00e9sitait certes entre son envie de devenir un cours d&#039;eau et sa vocation originale de chemin...\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_002\/3682764495.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Notre itin\u00e9raire h\u00e9sitait certes entre son envie de devenir un cours d'eau et sa vocation originale de chemin...<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_003.jpg\" data-caption-title=\"Un premier n\u00e9v\u00e9 r\u00e9calcitrant nous for\u00e7ait \u00e0 le contourner via un bref portage,..\" data-caption-desc=\"Un premier n\u00e9v\u00e9 r\u00e9calcitrant nous for\u00e7ait \u00e0 le contourner via un bref portage,..\" data-attachment-id=\"36804\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_003\" title=\"Un premier n\u00e9v\u00e9 r\u00e9calcitrant nous for\u00e7ait \u00e0 le contourner via un bref portage,..\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_003\/1039547594.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Un premier n\u00e9v\u00e9 r\u00e9calcitrant nous for\u00e7ait \u00e0 le contourner via un bref portage,..<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_004.jpg\" data-caption-title=\"... mais le petit vallon \u00e0 la c\u00e9l\u00e8bre ligne haute-tension transfrontali\u00e8re se laissait finalement mieux remonter que pr\u00e9vu.\" data-caption-desc=\"... mais le petit vallon \u00e0 la c\u00e9l\u00e8bre ligne haute-tension transfrontali\u00e8re se laissait finalement mieux remonter que pr\u00e9vu.\" data-attachment-id=\"36803\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_004\" title=\"... mais le petit vallon \u00e0 la c\u00e9l\u00e8bre ligne haute-tension transfrontali\u00e8re se laissait finalement mieux remonter que pr\u00e9vu.\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_004\/3811184658.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">... mais le petit vallon \u00e0 la c\u00e9l\u00e8bre ligne haute-tension transfrontali\u00e8re se laissait finalement mieux remonter que pr\u00e9vu.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_005.jpg\" data-caption-title=\"Enfin, parfois moins que mieux.\" data-caption-desc=\"Enfin, parfois moins que mieux.\" data-attachment-id=\"36802\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_005\" title=\"Enfin, parfois moins que mieux.\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_005\/90090007.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Enfin, parfois moins que mieux.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_006.jpg\" data-caption-title=\"Quand la fin du chemin, l&#039;arriv\u00e9e du brouillard, le vent forcissant et l&#039;absence de r\u00e9seau se sont conjugu\u00e9s, il aurait peut-\u00eatre fallu songer \u00e0 renoncer...\" data-caption-desc=\"Quand la fin du chemin, l&#039;arriv\u00e9e du brouillard, le vent forcissant et l&#039;absence de r\u00e9seau se sont conjugu\u00e9s, il aurait peut-\u00eatre fallu songer \u00e0 renoncer...\" data-attachment-id=\"36801\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_006\" title=\"Quand la fin du chemin, l&#039;arriv\u00e9e du brouillard, le vent forcissant et l&#039;absence de r\u00e9seau se sont conjugu\u00e9s, il aurait peut-\u00eatre fallu songer \u00e0 renoncer...\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_006\/4105331289.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Quand la fin du chemin, l'arriv\u00e9e du brouillard, le vent forcissant et l'absence de r\u00e9seau se sont conjugu\u00e9s, il aurait peut-\u00eatre fallu songer \u00e0 renoncer...<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_007.jpg\" data-caption-title=\"... ou pas !\" data-caption-desc=\"... ou pas !\" data-attachment-id=\"36800\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_007\" title=\"... ou pas !\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_007\/315021404.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">... ou pas !<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_008.jpg\" data-caption-title=\"La c\u00e9l\u00e8bre pente nord du col Ouest, version pieds tremp\u00e9es et \u00e9paules meurtries. Tout un programme.\" data-caption-desc=\"La c\u00e9l\u00e8bre pente nord du col Ouest, version pieds tremp\u00e9es et \u00e9paules meurtries. Tout un programme.\" data-attachment-id=\"36799\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_008\" title=\"La c\u00e9l\u00e8bre pente nord du col Ouest, version pieds tremp\u00e9es et \u00e9paules meurtries. Tout un programme.\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_008\/3551424712.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">La c\u00e9l\u00e8bre pente nord du col Ouest, version pieds tremp\u00e9es et \u00e9paules meurtries. Tout un programme.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_009.jpg\" data-caption-title=\"Cool, il fait (presque) beau en Italie !\" data-caption-desc=\"Cool, il fait (presque) beau en Italie !\" data-attachment-id=\"36798\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_009\" title=\"Cool, il fait (presque) beau en Italie !\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_009\/903531213.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Cool, il fait (presque) beau en Italie !<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_010.jpg\" data-caption-title=\"Enfin, surtout si on occulte la temp\u00eate de neige qui vient de nous rattraper et son vent d\u00e9sormais temp\u00e9tueux.\" data-caption-desc=\"Enfin, surtout si on occulte la temp\u00eate de neige qui vient de nous rattraper et son vent d\u00e9sormais temp\u00e9tueux.\" data-attachment-id=\"36797\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_010\" title=\"Enfin, surtout si on occulte la temp\u00eate de neige qui vient de nous rattraper et son vent d\u00e9sormais temp\u00e9tueux.\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_010\/1685271293.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Enfin, surtout si on occulte la temp\u00eate de neige qui vient de nous rattraper et son vent d\u00e9sormais temp\u00e9tueux.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><div class=\"fg-item fg-type-image fg-idle\"><figure class=\"fg-item-inner\"><a href=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/barasson_011.jpg\" data-caption-title=\"Mais ce ne sera finalement ni l&#039;une ni l&#039;autre qui nous inciteront \u00e0 retourner sur nos pas, mais bien le pseudo chemin du  versant aostien et sa totale inadaptation au bike.\" data-caption-desc=\"Mais ce ne sera finalement ni l&#039;une ni l&#039;autre qui nous inciteront \u00e0 retourner sur nos pas, mais bien le pseudo chemin du  versant aostien et sa totale inadaptation au bike.\" data-attachment-id=\"36796\" data-type=\"image\" class=\"fg-thumb\"><span class=\"fg-image-wrap\"><img decoding=\"async\" alt=\"barasson_011\" title=\"Mais ce ne sera finalement ni l&#039;une ni l&#039;autre qui nous inciteront \u00e0 retourner sur nos pas, mais bien le pseudo chemin du  versant aostien et sa totale inadaptation au bike.\" width=\"101\" height=\"57\" class=\"skip-lazy fg-image\" data-src-fg=\"https:\/\/alpavista.ch\/Alp11\/wp-content\/uploads\/cache\/barasson_011\/2181531896.jpg\" src=\"data:image\/svg+xml,%3Csvg%20xmlns%3D%22http%3A%2F%2Fwww.w3.org%2F2000%2Fsvg%22%20width%3D%22101%22%20height%3D%2257%22%20viewBox%3D%220%200%20101%2057%22%3E%3C%2Fsvg%3E\" loading=\"eager\"><\/span><span class=\"fg-image-overlay\"><\/span><\/a><figcaption class=\"fg-caption\"><div class=\"fg-caption-inner\"><div class=\"fg-caption-desc\">Mais ce ne sera finalement ni l'une ni l'autre qui nous inciteront \u00e0 retourner sur nos pas, mais bien le pseudo chemin du  versant aostien et sa totale inadaptation au bike.<\/div><\/div><\/figcaption><\/figure><div class=\"fg-loader\"><\/div><\/div><\/div>\n\n<input class=\"fooboxshare_post_id\" type=\"hidden\" value=\"5848\"\/>","protected":false},"excerpt":{"rendered":"<p>Partir reconna\u00eetre un nouveau parcours VTT est souvent hasardeux, tant il est difficile de pr\u00e9dire ce que les traits till\u00e9s de la carte r\u00e9v\u00e8leront sur le terrain. C\u2019est un principe de base, et en \u00ab principe \u00bb on le sait. Oui, mais il y a des reconnaissances plus \u00ab gal\u00e8res \u00bb que d\u2019autres. Comme par exemple celle qui consistait \u00e0 aller reconna\u00eetre le chemin transfrontalier passant par le(s) col(s) de Barasson, Est et Ouest, en juin, \u00e0 plus de 2&rsquo;600 [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":6146,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[658,4],"tags":[1071,1395,1138,1180,1072,1136,1137],"class_list":["post-5848","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-outdoor","category-vtt","tag-aoste","tag-barasson","tag-bourg-st-pierre","tag-dranse","tag-entremont","tag-grand-st-bernard","tag-toules"],"_links":{"self":[{"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/posts\/5848","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/comments?post=5848"}],"version-history":[{"count":0,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/posts\/5848\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/media\/6146"}],"wp:attachment":[{"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/media?parent=5848"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/categories?post=5848"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/alpavista.ch\/Alp11\/wp-json\/wp\/v2\/tags?post=5848"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}